{"id":1401,"date":"2023-03-30T05:46:00","date_gmt":"2023-03-30T05:46:00","guid":{"rendered":"https:\/\/orientados.co\/?p=1401"},"modified":"2023-04-20T05:49:52","modified_gmt":"2023-04-20T05:49:52","slug":"en-mula-la-alcaldia-de-el-carmen-llevo-internet-hasta-una-vereda-lejana","status":"publish","type":"post","link":"https:\/\/orientados.co\/index.php\/2023\/03\/30\/en-mula-la-alcaldia-de-el-carmen-llevo-internet-hasta-una-vereda-lejana\/","title":{"rendered":"En mula, la Alcald\u00eda de El Carmen llev\u00f3 internet hasta una vereda lejana"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"http:\/\/orientados.co\/wp-content\/uploads\/2023\/04\/C650E635-19B3-4B57-8EE2-136926C2067D-1024x682.jpeg\" alt=\"\" class=\"wp-image-1403\" srcset=\"https:\/\/orientados.co\/wp-content\/uploads\/2023\/04\/C650E635-19B3-4B57-8EE2-136926C2067D-1024x682.jpeg 1024w, https:\/\/orientados.co\/wp-content\/uploads\/2023\/04\/C650E635-19B3-4B57-8EE2-136926C2067D-300x200.jpeg 300w, https:\/\/orientados.co\/wp-content\/uploads\/2023\/04\/C650E635-19B3-4B57-8EE2-136926C2067D-768x512.jpeg 768w, https:\/\/orientados.co\/wp-content\/uploads\/2023\/04\/C650E635-19B3-4B57-8EE2-136926C2067D-1536x1023.jpeg 1536w, https:\/\/orientados.co\/wp-content\/uploads\/2023\/04\/C650E635-19B3-4B57-8EE2-136926C2067D.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Disminuir la brecha digital en el sector rural, es el objetivo de la Secretar\u00eda de Educaci\u00f3n de El Carmen de Viboral, quien a trav\u00e9s de una antena de internet satelital, conect\u00f3 a los ni\u00f1os y ni\u00f1as del Centro Educativo Rural de la vereda La Cristalina, hasta donde tuvieron que llegar montados en mula por varias horas.<\/p>\n\n\n\n<p>Este Centro Educativo Rural est\u00e1 ubicado en medio del ca\u00f1\u00f3n del R\u00edo Melcocho y desde ahora provee acceso a internet de banda ancha a estudiantes y campesinos; estos \u00faltimos tambi\u00e9n podr\u00e1n acceder a informaci\u00f3n sobre agronegocios, producci\u00f3n agr\u00edcola y emprendimientos de forma sencilla gracias a la conexi\u00f3n.<\/p>\n\n\n\n<p>\u201cLes trajimos internet y les dejamos conectada una antena satelital la cual va a ayudar much\u00edsimo con las actividades pedag\u00f3gicas que se desarrollan en la escuela. Es una alegr\u00eda inmensa llegar hasta esta vereda, donde los ni\u00f1os y ni\u00f1as tendr\u00e1n acceso a internet por primera vez desde sus escuelas\u201d, indic\u00f3 Mayely Giraldo, secretaria de Educaci\u00f3n municipal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Disminuir la brecha digital en el sector rural, es el objetivo de la Secretar\u00eda de Educaci\u00f3n de El Carmen de Viboral, quien a trav\u00e9s de una antena de internet satelital,&hellip; <\/p>\n","protected":false},"author":1,"featured_media":1402,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_mi_skip_tracking":false,"footnotes":""},"categories":[1],"tags":[137,198,197],"class_list":["post-1401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-el-carmen-de-viboral","tag-en-mula","tag-internet"],"_links":{"self":[{"href":"https:\/\/orientados.co\/index.php\/wp-json\/wp\/v2\/posts\/1401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orientados.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orientados.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orientados.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/orientados.co\/index.php\/wp-json\/wp\/v2\/comments?post=1401"}],"version-history":[{"count":1,"href":"https:\/\/orientados.co\/index.php\/wp-json\/wp\/v2\/posts\/1401\/revisions"}],"predecessor-version":[{"id":1404,"href":"https:\/\/orientados.co\/index.php\/wp-json\/wp\/v2\/posts\/1401\/revisions\/1404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orientados.co\/index.php\/wp-json\/wp\/v2\/media\/1402"}],"wp:attachment":[{"href":"https:\/\/orientados.co\/index.php\/wp-json\/wp\/v2\/media?parent=1401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orientados.co\/index.php\/wp-json\/wp\/v2\/categories?post=1401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orientados.co\/index.php\/wp-json\/wp\/v2\/tags?post=1401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}